{"id":34815,"date":"2025-06-26T09:30:58","date_gmt":"2025-06-26T07:30:58","guid":{"rendered":"https:\/\/www.onlineprinters.de\/magazin\/?p=34815"},"modified":"2025-06-28T19:50:06","modified_gmt":"2025-06-28T17:50:06","slug":"wiedererkennungswert","status":"publish","type":"post","link":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/","title":{"rendered":"Der Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel (Gestaltungsregel #3)"},"content":{"rendered":"<p>So unterschiedlich auch die Anspr\u00fcche an eine Gestaltung sein k\u00f6nnen \u2013 die Basis einer jeden Gestaltung beruht auf allgemeing\u00fcltigen Regeln. Wir haben drei Gestaltungsregeln entwickelt, die bei jedem Design g\u00fcltig und hilfreich sind und die Grundlage der Gestaltung bilden. Die erste Regel <a href=\"https:\/\/www.onlineprinters.de\/magazin\/blickfang-gestaltungsregel-1\/\">Blickfang setzen<\/a> und die zweite Regel <a href=\"https:\/\/www.onlineprinters.de\/magazin\/gruppen-bilden-gestaltungsregel-2\/\">Gruppen bilden<\/a> haben wir bereits besprochen. Heute folgt die dritte Regel, die lautet: <strong>Wiedererkennungswert<\/strong><strong> schaffen.<\/strong><\/p>\n<p><strong>Inhalt<\/strong><\/p>\n<ul>\n<li><a href=\"#video\">Video-Tutorial zum Wiedererkennungswert<\/a><\/li>\n<li><a href=\"#sicherheit\">Der Wiedererkennungswert bedeutet Sicherheit<\/a><\/li>\n<li><a href=\"#wie\">Wie entsteht der Wiedererkennungswert?<\/a><\/li>\n<li><a href=\"#logo\">Das Logo als Teil der Wiedererkennung<\/a><\/li>\n<li><a href=\"#medien\">Medien\u00fcbergreifenden Wiedererkennungswert schaffen<\/a><\/li>\n<li><a href=\"#innerhalb\">Wiedererkennung schaffen innerhalb einer Gestaltung<\/a><\/li>\n<li><a href=\"#bausteine\">Bausteine der Wiederholung<\/a><\/li>\n<li><a href=\"#klare\">Wiedererkennung schaffen durch klare Gestaltung<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Video-Tutorial zum Wiedererkennungswert<\/h2>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/QRI0rO9FMqI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><br \/>\n<a name=\"sicherheit\"><\/a><\/p>\n<h2>Der Wiedererkennungswert bedeutet Sicherheit<\/h2>\n<p>Vorg\u00e4nge, die durch Gewohnheiten hervorgerufen werden, ben\u00f6tigen keine langen \u00dcberlegungen. Sie geschehen einfach, fast reflexartig. Wir m\u00fcssen nicht \u00fcberlegen, wir reagieren automatisch. Solche Vorg\u00e4nge geschehen sehr viel schneller als die, bei denen wir erst bewusst eine Entscheidung treffen m\u00fcssen. Dabei spielt es keine Rolle, ob wir regelm\u00e4\u00dfig zu einem bestimmten Produkt greifen oder ob wir jeden Morgen auf der Startseite rechts oben die blau hinterlegten Wirtschaftsnews \u00fcberfliegen \u2013<strong> wir erkennen ein Produkt oder eine Information wieder, und f\u00fchlen uns damit wohl<\/strong>.<br \/>\n<a name=\"wie\"><\/a><\/p>\n<h2>Wie entsteht der Wiedererkennungswert?<\/h2>\n<p>Wiedererkennung schaffen gelingt durch <strong>Wiederholung<\/strong>. In monatlich erscheinenden Magazinen oder der Nachrichtenseite im Internet sind die <span style=\"background-color: #0000ff; color: #ffffff;\">Interviews <\/span>immer blau hinterlegt; die <span style=\"background-color: #ff9900;\">Infok\u00e4sten<\/span> orange und der <em>Autorname<\/em> immer in kursiver Schrift. Somit wei\u00df der Leser beim Aufschlagen des Heftes oder beim \u00d6ffnen der Website genau, wie er sich orientieren kann. <strong>Er f\u00fchlt sich sicher, weil er sich auskennt<\/strong>. Er kann Informationsarten anhand von optischen Merkmalen sofort zuordnen.<\/p>\n<div class=\"custom-background-grey\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34825 size-large\" src=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung-1024x675.jpg\" alt=\"Ein leuchtend orangefarbenes Banner oben zeigt den fettgedruckten schwarzen Text \u201ePrint wirkt\u201c und sorgt f\u00fcr eine hohe Wiedererkennung. Darunter verl\u00e4uft ein dunkler Hintergrund mit Farbverlauf von Schwarz an den R\u00e4ndern zu einem helleren Grau in der Mitte.\" width=\"696\" height=\"459\" srcset=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung-1024x675.jpg 1024w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung-300x198.jpg 300w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung-768x506.jpg 768w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung-1536x1012.jpg 1536w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung-696x458.jpg 696w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung-1068x704.jpg 1068w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung-638x420.jpg 638w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung.jpg 1559w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/p>\n<p><em><span style=\"font-size: 10pt;\">Die Kampagne &#8222;Print wirkt&#8220; zeigt eindrucksvoll, wie stark gestalterische Elemente wie Schriftart und Farbe bzw. Raumaufteilung und deren kontinuierliche Wiederholung Assoziationen beim Betrachter hervorruft.<\/span><\/em><\/p>\n<\/div>\n<p><a name=\"logo\"><\/a><\/p>\n<h2>Das Logo als Teil der Wiedererkennung<\/h2>\n<p>Mit dem Begriff Wiedererkennung verbinden sicher alle Gestalter schnell das Logo, ein Paradebeispiel f\u00fcr die Bedeutung von Wiedererkennung in der Werbung. Das Logo als Erkennungsmerkmal eines Unternehmens ist Teil des visuellen Erscheinungsbildes. Ziel ist es, dass der Kunde das Unternehmen anhand des Logos erkennt. Diese Wiedererkennung funktioniert mit einem <strong>grafischen Zeichen<\/strong> weitaus einfacher als mit Text, da das <strong>Logo<\/strong> \u00fcber eine <strong>Signalwirkung<\/strong> verf\u00fcgt und sich <strong>leichter einpr\u00e4gen<\/strong> l\u00e4sst.<\/p>\n<div class=\"custom-background-grey\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34822\" src=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Logo3.jpg\" alt=\"Die ikonische blaue Silhouette eines Vogels, der f\u00fcr seinen Wiedererkennungswert ber\u00fchmt ist, ist allgemein als Twitter-Logo bekannt. Vor einem wei\u00dfen Hintergrund blickt der Vogel nach rechts und hat elegant nach oben ausgebreitete Fl\u00fcgel.\" width=\"244\" height=\"179\" srcset=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Logo3.jpg 297w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Logo3-80x60.jpg 80w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34820\" src=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Logo1-247x300.jpg\" alt=\"Das silbermetallicfarbene Apple-Logo mit seiner markanten angebissenen Apfelform und dem abgetrennten Blatt verf\u00fcgt \u00fcber einen hohen Wiedererkennungswert.\" width=\"147\" height=\"179\" srcset=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Logo1-247x300.jpg 247w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Logo1.jpg 311w\" sizes=\"auto, (max-width: 147px) 100vw, 147px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-34821\" src=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Logo2.jpg\" alt=\"Gr\u00fcner Kreis mit drei dicken, schwarzen, geschwungenen Linien, die in seinem Kern horizontal \u00fcbereinander angeordnet sind und Schallwellen darstellen. Die Kurven des Designs spiegeln das Spotify-Logo wider und bieten einen hohen Wiedererkennungswert.\" width=\"184\" height=\"179\" \/><\/p>\n<p><em><span style=\"font-size: 10pt;\">Gut eingef\u00fchrte Logos funktionieren auch ohne Text bzw. Firmennamen &#8211; die Wiederholung macht\u2019s.<\/span><\/em><\/p>\n<\/div>\n<p><a name=\"medien\"><\/a><\/p>\n<h2>Medien\u00fcbergreifenden Wiedererkennungswert schaffen<\/h2>\n<p>Die Bedeutung von Wiedererkennung geht aber noch viel weiter, und genau genommen begegnen wir Gestalter ihr t\u00e4glich, auch wenn wir nicht jeden Tag ein Logo gestalten. Wiedererkennung schaffen hei\u00dft n\u00e4mlich auch, <strong>medien\u00fcbergreifend<\/strong> so zu gestalten, dass eine Verbindung sichtbar ist. Wer im Corporate Design arbeitet, wei\u00df, dass es nicht gen\u00fcgt, auf die Visitenkarte, das Briefpapier und den Flyer \u201enur\u201c das Unternehmenslogo zu platzieren. Wir m\u00fcssen so gestalten, dass <strong>alle zusammengeh\u00f6rigen Produkte optisch als zusammengeh\u00f6rend erkannt werden<\/strong> k\u00f6nnen. Gestaltungen wie Produktbl\u00e4tter, die in eine Kategorie geh\u00f6ren bzw. inhaltlich vergleichbare Informationen vermitteln, sollten gleich gestaltet sein. So muss die Visitenkarte zum <a href=\"https:\/\/www.onlineprinters.de\/k\/briefpapier\" target=\"_blank\" rel=\"noopener noreferrer\">Briefpapier<\/a>, <a href=\"https:\/\/www.onlineprinters.de\/k\/flyer\" target=\"_blank\" rel=\"noopener noreferrer\">Flyer<\/a>, <a href=\"https:\/\/www.onlineprinters.de\/k\/broschueren\" target=\"_blank\" rel=\"noopener noreferrer\">Jahresbericht<\/a>, <a href=\"https:\/\/www.onlineprinters.de\/k\/messesysteme\" target=\"_blank\" rel=\"noopener noreferrer\">Messestand<\/a> und zur Website passen, damit wir Wiedererkennung schaffen.<\/p>\n<div class=\"custom-background-grey\">\n<p><a href=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Eis_Brief.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-34818\" src=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Eis_Brief.jpg\" alt=\"In einem Brief auf Markenbriefpapier mit dem unverwechselbaren Erdbeerlogo von \u201eErdbeere und Freunde\u201c geht es um Lieferverz\u00f6gerungen. Der Brief ist auf den 11. Januar 2019 datiert und enth\u00e4lt eine Fortsetzung vom 30. Januar, in der saisonale Men\u00fc\u00e4nderungen und Lieferantenprobleme besprochen werden und der hohe Wiedererkennungswert der Marke hervorgehoben wird.\" width=\"394\" height=\"558\" srcset=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Eis_Brief.jpg 681w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Eis_Brief-212x300.jpg 212w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Eis_Brief-296x420.jpg 296w\" sizes=\"auto, (max-width: 394px) 100vw, 394px\" \/><\/a><a href=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Eis_VK.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-34819\" src=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Eis_VK.jpg\" alt=\"Das Bild zeigt eine Visitenkarte von \u201eEis am Torplatz\u201c, bekannt f\u00fcr seinen einzigartigen Wiedererkennungswert. Auf der linken Seite steht: \u201eTorplatz 12, 58115 Bonn, Montag\u2013Freitag 13.00\u201319.00 Uhr.\u201c Ein roter Kreis auf der rechten Seite hebt \u201eErdbeere &amp; Freunde\u201c in wei\u00dfer Kursivschrift hervor.\" width=\"230\" height=\"133\" \/><\/a><\/p>\n<p><em><span style=\"font-size: 10pt;\">Der Briefbogen und die Visitenkarte sind stringent gestaltet.<\/span><\/em><\/p>\n<\/div>\n<h3>Der Einsatz des Logos in der Praxis<\/h3>\n<p>Das Logo muss <strong>nicht<\/strong> auf jedem Produkt in der gleichen Gr\u00f6\u00dfe und an der gleichen Stelle auftauchen. Wichtig ist, <strong>dass es auftaucht<\/strong>. Der Betrachter nimmt es aber auch wahr, wenn es nicht in vorderster Front gro\u00df zu sehen ist, sondern vielleicht nur aufgehellt im Hintergrund liegt. Oder wenn nur Teile davon zu sehen sind. Sie k\u00f6nnen also guten Gewissens mit der <strong>Gr\u00f6\u00dfe<\/strong> und der <strong>Deckkraft<\/strong> spielen. Die <strong>Farbe<\/strong> sollte allerdings m\u00f6glichst <strong>unver\u00e4ndert<\/strong> verwendet werden, da <em>Farbe ein starker Indikator f\u00fcr die Wiedererkennung<\/em> ist. Einige Unternehmen verf\u00fcgen in ihrer Corporate Identity standardm\u00e4\u00dfig \u00fcber zwei oder drei Farbvarianten, die dann in jedem Fall ausreichen sollten.<\/p>\n<div class=\"custom-background-grey\">\n<p><a href=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_Brief.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-34823\" src=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_Brief.jpg\" alt=\"Der Briefkopf mit einer Zahnillustration in der Mitte unterstreicht den Wiedererkennungswert von Zahnarzt Mundwerk. Kontaktdaten finden sich oben rechts und unten links. Der Brief, adressiert an \u201eFrau Meyer\u201c und datiert auf den 12.11.2019, spiegelt eine klare berufliche Identit\u00e4t wider.\" width=\"384\" height=\"543\" srcset=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_Brief.jpg 682w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_Brief-212x300.jpg 212w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_Brief-297x420.jpg 297w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/a><a href=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_VK.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"td-modal-image alignnone wp-image-34824\" src=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_VK.jpg\" alt=\"Visitenkarte f\u00fcr Zahnartz Mundwerk mit markantem Zahnsymbol. Inklusive Kontaktdaten von Sofia Blomberl: Bettmayerstra\u00dfe 134, 38100 Braunschweig, Tel: 0531\/654569, Fax: 0531\/654589, E-Mail: info@zahnmundwerk.de, Web: www.zahnmundwerk.de.\" width=\"233\" height=\"150\" srcset=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_VK.jpg 736w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_VK-300x194.jpg 300w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_VK-696x450.jpg 696w, https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2021\/09\/Gestaltungsregel_3_Wiederholung_Mundwerk_VK-649x420.jpg 649w\" sizes=\"auto, (max-width: 233px) 100vw, 233px\" \/><\/a><\/p>\n<p><span style=\"font-size: 10pt;\"><em>Ein klares Logo l\u00e4sst sich auch in abgewandelter Form verwenden und f\u00fchrt trotzdem zum Wiedererkennungseffekt.<\/em><\/span><\/p>\n<\/div>\n<p><a name=\"innerhalb\"><\/a><\/p>\n<h2>Wiedererkennung schaffen innerhalb einer Gestaltung<\/h2>\n<p>Das Prinzip der Wiedererkennung innerhalb eines Gestaltungsobjekts wird h\u00e4ufig untersch\u00e4tzt, ist aber auch elementar. Auch innerhalb eines Mediums sollte der Betrachter die Logik von Gestaltungselementen nachvollziehen k\u00f6nnen. Klar, in einem Magazin sollten alle Artikel nach dem gleichen System aufgebaut sein, sodass sp\u00e4testens nach dem dritten Artikel leicht ersichtlich ist, wie die Infobox aussieht und wo die Zusatzinfos platziert sind. Wir k\u00f6nnen die Bedeutung von Wiederholung aber noch weiter herunterbrechen, sogar auf eine einseitigen Gestaltung. Denken Sie nur an <strong>wiederkehrende Farben oder Aufz\u00e4hlungszeichen<\/strong> \u2013 wie w\u00fcrde es auf den Betrachter wirken, wenn alle f\u00fcnf Aufz\u00e4hlungspunkte unterschiedlich aussehen w\u00fcrden.<br \/>\n<a name=\"bausteine\"><\/a><\/p>\n<h2>Bausteine der Wiederholung<\/h2>\n<p>Um Wiederholung zu visualisieren, haben wir viele M\u00f6glichkeiten. Ganz vorn steht sicherlich die <strong>Farbe<\/strong>, die einen gro\u00dfen Baustein bei der Wiedererkennung darstellt \u2013 und zudem auch noch die emotionale Ebene anspricht. Neben der Farbe ist die <strong>Schrift<\/strong> ein bedeutendes Element in der Gestaltung \u2013 und somit auch bei der Wiedererkennung, und nicht umsonst sind Farbe und Schrift in jedem Corporate Design-Handbuch vertreten. Dabei ist es nicht nur die Schriftart, sondern auch die <em>Schnitte<\/em>, <em>Gr\u00f6\u00dfen<\/em> und eventuelle Eingriffe in die <em>Laufweiten<\/em> oder <em>Zeilenabst\u00e4nde<\/em>, die durch regelm\u00e4\u00dfige, wiederkehrende und konsistente Anwendung zur Wiedererkennung beim Betrachter f\u00fchren. Und nicht zuletzt sind es alle weiteren <strong>grafischen Elemente<\/strong> und <strong>Stilmittel<\/strong> wie <em>grafische Figuren<\/em>, <em>Formen<\/em>, <em>Unterstreichungen<\/em>, <em>Farbhintergr\u00fcnde<\/em> oder <em>Linien<\/em>, die das Gesamtbild formen. Das f\u00fchrt zum n\u00e4chsten Punkt:<br \/>\n<a name=\"klare\"><\/a><\/p>\n<h2>Wiedererkennung schaffen durch klare Gestaltung<\/h2>\n<p>\u201eEin Zeichen ist gut, wenn man es mit dem gro\u00dfen Zeh in den Sand kratzen kann\u201c, hat Kurt Weidemann gesagt. Das trifft nicht nur auf ein Logo zu. Auch ganze Gestaltungen sind gut, wenn sie einpr\u00e4gsam sind. Und einpr\u00e4gsam kann nur sein, was klar ist \u2013 Ausnahmen best\u00e4tigen die Regel.<\/p>\n<div class=\"custom-background-grey\">\n<p><strong>Mehr zum Thema Gestaltungsregeln finden Sie hier:<\/strong><\/p>\n<p class=\"entry-title\">Regel #1: <a href=\"https:\/\/www.onlineprinters.de\/magazin\/blickfang-gestaltungsregel-1\/\">Blickfang setzen: So werden Flyer und Co. zum Eyecatcher<\/a><br \/>\nRegel #2: <a href=\"https:\/\/www.onlineprinters.de\/magazin\/gruppen-bilden-gestaltungsregel-2\/\">Gruppen bilden: Zusammenh\u00e4nge sichtbar machen und freie R\u00e4ume nutzen<\/a><br \/>\nRegel #3: Der Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel (dieser Artikel)<\/p>\n<\/div>\n<div class=\"custom-background-grey\">\n<p><strong>Bildquellen:<\/strong> Arek Sochay, mohamed Hassan, seagul via <a href=\"https:\/\/pixabay.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Pixabay<\/a><\/p>\n<p><strong>Credits:<\/strong>\u00a0Es gestaltet und spricht Claudia Korthaus (Typostil).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wiedererkennung schaffen ist die dritte der drei Gestaltungsregeln. Wir zeigen, warum Wiedererkennung wichtig ist und wie wir sie erreichen.<\/p>\n","protected":false},"author":44,"featured_media":35969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,5,9],"tags":[],"class_list":["post-34815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-artikel","category-design","category-design-wissen","post_overlay_tag-praxis-tipps"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel<\/title>\n<meta name=\"description\" content=\"Der Wiedererkennungswert ist die dritte der drei Gestaltungsregeln. Wir zeigen, warum Wiedererkennung wichtig ist und wie wir sie erreichen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel\" \/>\n<meta property=\"og:description\" content=\"Der Wiedererkennungswert ist die dritte der drei Gestaltungsregeln. Wir zeigen, warum Wiedererkennung wichtig ist und wie wir sie erreichen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/\" \/>\n<meta property=\"og:site_name\" content=\"Onlineprinters Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-26T07:30:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-28T17:50:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2022\/01\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1068\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claudia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/\"},\"author\":{\"name\":\"Claudia\",\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/#\\\/schema\\\/person\\\/62c9f19fb18c4d78c9598e92c0793791\"},\"headline\":\"Der Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel (Gestaltungsregel #3)\",\"datePublished\":\"2025-06-26T07:30:58+00:00\",\"dateModified\":\"2025-06-28T17:50:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/\"},\"wordCount\":1016,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg\",\"articleSection\":[\"1_Design-Top-Artikel\",\"Design\",\"Design Wissen &amp; Hintergrund\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/\",\"url\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/\",\"name\":\"Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg\",\"datePublished\":\"2025-06-26T07:30:58+00:00\",\"dateModified\":\"2025-06-28T17:50:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/#\\\/schema\\\/person\\\/62c9f19fb18c4d78c9598e92c0793791\"},\"description\":\"Der Wiedererkennungswert ist die dritte der drei Gestaltungsregeln. Wir zeigen, warum Wiedererkennung wichtig ist und wie wir sie erreichen.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wiedererkennungswert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg\",\"contentUrl\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg\",\"width\":1068,\"height\":580},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/\",\"name\":\"Onlineprinters Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/#\\\/schema\\\/person\\\/62c9f19fb18c4d78c9598e92c0793791\",\"name\":\"Claudia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/image-150x150.jpg\",\"url\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/image-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/image-150x150.jpg\",\"caption\":\"Claudia\"},\"sameAs\":[\"http:\\\/\\\/www.typostil.de\"],\"url\":\"https:\\\/\\\/www.onlineprinters.de\\\/magazin\\\/author\\\/claudia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel","description":"Der Wiedererkennungswert ist die dritte der drei Gestaltungsregeln. Wir zeigen, warum Wiedererkennung wichtig ist und wie wir sie erreichen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/","og_locale":"de_DE","og_type":"article","og_title":"Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel","og_description":"Der Wiedererkennungswert ist die dritte der drei Gestaltungsregeln. Wir zeigen, warum Wiedererkennung wichtig ist und wie wir sie erreichen.","og_url":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/","og_site_name":"Onlineprinters Magazin","article_published_time":"2025-06-26T07:30:58+00:00","article_modified_time":"2025-06-28T17:50:06+00:00","og_image":[{"width":1068,"height":580,"url":"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2022\/01\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg","type":"image\/jpeg"}],"author":"Claudia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/#article","isPartOf":{"@id":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/"},"author":{"name":"Claudia","@id":"https:\/\/www.onlineprinters.de\/magazin\/#\/schema\/person\/62c9f19fb18c4d78c9598e92c0793791"},"headline":"Der Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel (Gestaltungsregel #3)","datePublished":"2025-06-26T07:30:58+00:00","dateModified":"2025-06-28T17:50:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/"},"wordCount":1016,"commentCount":0,"image":{"@id":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2022\/01\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg","articleSection":["1_Design-Top-Artikel","Design","Design Wissen &amp; Hintergrund"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/","url":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/","name":"Wiedererkennungswert \u2013 die Wiederholung als Gestaltungsmittel","isPartOf":{"@id":"https:\/\/www.onlineprinters.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/#primaryimage"},"image":{"@id":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/#primaryimage"},"thumbnailUrl":"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2022\/01\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg","datePublished":"2025-06-26T07:30:58+00:00","dateModified":"2025-06-28T17:50:06+00:00","author":{"@id":"https:\/\/www.onlineprinters.de\/magazin\/#\/schema\/person\/62c9f19fb18c4d78c9598e92c0793791"},"description":"Der Wiedererkennungswert ist die dritte der drei Gestaltungsregeln. Wir zeigen, warum Wiedererkennung wichtig ist und wie wir sie erreichen.","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.onlineprinters.de\/magazin\/wiedererkennungswert\/#primaryimage","url":"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2022\/01\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg","contentUrl":"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2022\/01\/Beitragsbild_Gestsaltungsregel-3-Wiedererkennungswert.jpg","width":1068,"height":580},{"@type":"WebSite","@id":"https:\/\/www.onlineprinters.de\/magazin\/#website","url":"https:\/\/www.onlineprinters.de\/magazin\/","name":"Onlineprinters Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.onlineprinters.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.onlineprinters.de\/magazin\/#\/schema\/person\/62c9f19fb18c4d78c9598e92c0793791","name":"Claudia","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2019\/02\/image-150x150.jpg","url":"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2019\/02\/image-150x150.jpg","contentUrl":"https:\/\/www.onlineprinters.de\/magazin\/wp-content\/uploads\/2019\/02\/image-150x150.jpg","caption":"Claudia"},"sameAs":["http:\/\/www.typostil.de"],"url":"https:\/\/www.onlineprinters.de\/magazin\/author\/claudia\/"}]}},"_links":{"self":[{"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/posts\/34815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/comments?post=34815"}],"version-history":[{"count":19,"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/posts\/34815\/revisions"}],"predecessor-version":[{"id":42590,"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/posts\/34815\/revisions\/42590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/media\/35969"}],"wp:attachment":[{"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/media?parent=34815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/categories?post=34815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.onlineprinters.de\/magazin\/wp-json\/wp\/v2\/tags?post=34815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}